{"id":858,"date":"2016-06-03T16:01:57","date_gmt":"2016-06-03T07:01:57","guid":{"rendered":"http:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/?p=858"},"modified":"2016-06-03T16:01:57","modified_gmt":"2016-06-03T07:01:57","slug":"%e6%b0%b4%e6%8a%9c%e3%81%8d%e6%b8%85%e6%8e%83%e3%81%97%e3%81%be%e3%81%97%e3%81%9f%e3%80%82","status":"publish","type":"post","link":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/2016\/06\/03\/%e6%b0%b4%e6%8a%9c%e3%81%8d%e6%b8%85%e6%8e%83%e3%81%97%e3%81%be%e3%81%97%e3%81%9f%e3%80%82\/","title":{"rendered":"\u6c34\u629c\u304d\u6e05\u6383\u3057\u307e\u3057\u305f\u3002"},"content":{"rendered":"<p><FONT color=\"#0000FF\" size=\"4\">\uff16\u6708\uff11\u65e5\uff08\u6c34\uff09\uff12\u65e5\uff08\u6728\uff09\u6c34\u3092\u629c\u304d\u30d7\u30fc\u30eb\u5185\u3001\u66f4\u8863\u5ba4\u7b49\u306e\u6e05\u6383\u3092\u5b9f\u65bd\u3057\u307e\u3057\u305f\u3002<\/FONT><\/p>\n<p><a href=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/fa6b9982da74ecc793e9931ed32d724e.jpg\" rel=\"lightbox[858]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/fa6b9982da74ecc793e9931ed32d724e.jpg\" alt=\"\" width=\"516\" height=\"387\" class=\"aligncenter size-full wp-image-861\" srcset=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/fa6b9982da74ecc793e9931ed32d724e.jpg 516w, https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/fa6b9982da74ecc793e9931ed32d724e-300x225.jpg 300w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/a><\/p>\n<p><FONT color=\"#0000FF\" size=\"4\">\u96fb\u7403\u306e\u4ea4\u63db\u3082\u5b9f\u65bd<\/FONT><\/p>\n<p><a href=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/e23e4aacb9992e11f7993d857f6eb52b1.jpg\" rel=\"lightbox[858]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/e23e4aacb9992e11f7993d857f6eb52b1.jpg\" alt=\"\" width=\"516\" height=\"387\" class=\"aligncenter size-full wp-image-863\" srcset=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/e23e4aacb9992e11f7993d857f6eb52b1.jpg 516w, https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/e23e4aacb9992e11f7993d857f6eb52b1-300x225.jpg 300w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/731fb56d70fef6f9b1fd0d19da99f5dc2.jpg\" rel=\"lightbox[858]\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/731fb56d70fef6f9b1fd0d19da99f5dc2.jpg\" alt=\"\" width=\"516\" height=\"387\" class=\"aligncenter size-full wp-image-865\" srcset=\"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/731fb56d70fef6f9b1fd0d19da99f5dc2.jpg 516w, https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/files\/2016\/06\/731fb56d70fef6f9b1fd0d19da99f5dc2-300x225.jpg 300w\" sizes=\"auto, (max-width: 516px) 100vw, 516px\" \/><\/a><br \/>\n<FONT color=\"#0000FF\" size=\"4\">\u307f\u3093\u306a\u3067\u30b4\u30b7\u30b4\u30b7\u6c5a\u308c\u3092\u304a\u3068\u3057\u3066\u3044\u307e\u3059\u3002<\/FONT><\/p>\n<p><FONT color=\"#0000FF\" size=\"4\">\u672c\u65e5\u306e\u6607\u6e29\u3082\u9806\u8abf\u3067\u3059\u3002\u660e\u65e5\uff08\uff16\u6708\uff14\u65e5(\u571f\uff09\uff09\u3088\u308a\u901a\u5e38\u3069\u304a\u308a\u30d7\u30fc\u30eb\u306e\u55b6\u696d\u3092\u884c\u3044\u307e\u3059\u3002<BR><BR>\u7686\u69d8\u306e\u3054\u6765\u5834\u304a\u5f85\u3061\u3057\u3066\u304a\u308a\u307e\u3059\u3002<\/FONT><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\uff16\u6708\uff11\u65e5\uff08\u6c34\uff09\uff12\u65e5\uff08\u6728\uff09\u6c34\u3092\u629c\u304d\u30d7\u30fc\u30eb\u5185\u3001\u66f4\u8863\u5ba4\u7b49\u306e\u6e05\u6383\u3092\u5b9f\u65bd\u3057\u307e\u3057\u305f\u3002 \u96fb\u7403\u306e\u4ea4\u63db\u3082\u5b9f\u65bd \u307f\u3093\u306a\u3067\u30b4\u30b7\u30b4\u30b7\u6c5a\u308c\u3092\u304a\u3068\u3057\u3066\u3044\u307e\u3059\u3002 \u672c\u65e5\u306e\u6607\u6e29\u3082\u9806\u8abf\u3067\u3059\u3002\u660e\u65e5\uff08\uff16\u6708\uff14\u65e5(\u571f\uff09\uff09\u3088\u308a\u901a\u5e38\u3069\u304a\u308a\u30d7\u30fc\u30eb\u306e\u55b6\u696d\u3092\u884c\u3044\u307e\u3059\u3002\u7686\u69d8\u306e [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-858","post","type-post","status-publish","format-standard","hentry","category-1"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:11:05","action":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/posts\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":7,"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/posts\/858\/revisions"}],"predecessor-version":[{"id":871,"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/posts\/858\/revisions\/871"}],"wp:attachment":[{"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/media?parent=858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/categories?post=858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nespa.or.jp\/blog\/biwajima_sc\/wp-json\/wp\/v2\/tags?post=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}